{"id":5,"count":6,"description":"","link":"https:\/\/siliconcarbidepowders.com\/ar\/%d8%a7%d9%84%d9%81%d8%a6%d8%a9\/%d8%a7%d9%84%d9%85%d9%86%d8%aa%d8%ac\/","name":"\u0627\u0644\u0645\u0646\u062a\u062c","slug":"%d8%a7%d9%84%d9%85%d9%86%d8%aa%d8%ac","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/siliconcarbidepowders.com\/ar\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siliconcarbidepowders.com\/ar\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/siliconcarbidepowders.com\/ar\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/siliconcarbidepowders.com\/ar\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}