{"id":2,"count":2,"description":"","link":"https:\/\/siliconcarbidepowders.com\/et\/kategooria\/uudised\/","name":"Uudised","slug":"uudised","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/siliconcarbidepowders.com\/et\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siliconcarbidepowders.com\/et\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/siliconcarbidepowders.com\/et\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/siliconcarbidepowders.com\/et\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}