{"id":5,"count":6,"description":"","link":"https:\/\/siliconcarbidepowders.com\/hr\/kategorija\/proizvod\/","name":"proizvod","slug":"proizvod","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/siliconcarbidepowders.com\/hr\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siliconcarbidepowders.com\/hr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/siliconcarbidepowders.com\/hr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/siliconcarbidepowders.com\/hr\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}