{"id":1,"name":"admin88","url":"http:\/\/siliconcarbidepowders.com","description":"","link":"https:\/\/siliconcarbidepowders.com\/id\/author\/admin88\/","slug":"admin88","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/796c0c0b75832ed150ff830b732e6ddcbcc7da7505d356fa7f758ccca1bba82f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/796c0c0b75832ed150ff830b732e6ddcbcc7da7505d356fa7f758ccca1bba82f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/796c0c0b75832ed150ff830b732e6ddcbcc7da7505d356fa7f758ccca1bba82f?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"https:\/\/siliconcarbidepowders.com\/id\/wp-json\/wp\/v2\/users\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siliconcarbidepowders.com\/id\/wp-json\/wp\/v2\/users"}]}}