{"id":2,"count":2,"description":"","link":"https:\/\/siliconcarbidepowders.com\/ka\/%e1%83%99%e1%83%90%e1%83%a2%e1%83%94%e1%83%92%e1%83%9d%e1%83%a0%e1%83%98%e1%83%90\/%e1%83%a1%e1%83%98%e1%83%90%e1%83%ae%e1%83%9a%e1%83%94%e1%83%94%e1%83%91%e1%83%98\/","name":"\u10d0\u10ee\u10d0\u10da\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8","slug":"%e1%83%a1%e1%83%98%e1%83%90%e1%83%ae%e1%83%9a%e1%83%94%e1%83%94%e1%83%91%e1%83%98","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/siliconcarbidepowders.com\/ka\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siliconcarbidepowders.com\/ka\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/siliconcarbidepowders.com\/ka\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/siliconcarbidepowders.com\/ka\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}