{"id":5,"count":6,"description":"","link":"https:\/\/siliconcarbidepowders.com\/ko\/%ec%b9%b4%ed%85%8c%ea%b3%a0%eb%a6%ac\/%ec%a0%9c%ed%92%88\/","name":"\uc81c\ud488","slug":"%ec%a0%9c%ed%92%88","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/siliconcarbidepowders.com\/ko\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siliconcarbidepowders.com\/ko\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/siliconcarbidepowders.com\/ko\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/siliconcarbidepowders.com\/ko\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}